{"id":159,"date":"2021-01-17T20:34:28","date_gmt":"2021-01-17T18:34:28","guid":{"rendered":"http:\/\/ukraine-forum.eu\/?post_type=ua-history&#038;p=159"},"modified":"2021-08-01T14:38:19","modified_gmt":"2021-08-01T11:38:19","slug":"kruty-pochatok-novoyi-doby-v-istoriyi-ukrayiny","status":"publish","type":"ua-history","link":"https:\/\/ukraine-forum.eu\/de\/ua-history\/kruty-pochatok-novoyi-doby-v-istoriyi-ukrayiny\/","title":{"rendered":"Kruty \u2013 der Beginn einer neuen Epoche in der ukrainischen Geschichte"},"content":{"rendered":"<p>Es gibt keinen gr\u00f6\u00dferen Mut, als seinen letzten Atemzug zu tun, um f\u00fcr seine eigenen Ideen und Pl\u00e4ne einzustehen. Die Studenten, die im Kampf f\u00fcr die Idee einer unabh\u00e4ngigen Ukraine am Bahnhof Kruty starben, sind ein Beispiel f\u00fcr diesen Mut. Der 29. Januar 1918 ist ein Tag, der zu einem Beispiel f\u00fcr Heldentaten und den Sieg der Ukraine und ihrer Unabh\u00e4ngigkeit geworden ist. Ihr Beispiel zeigt, dass die Freiheit und das Schicksal unseres Landes von der Bereitschaft jedes Ukrainers abh\u00e4ngen, die Interessen seines Landes zu achten und zu verteidigen.<\/p>\n<p>An jenem kalten Tag standen sehr junge, aber unbesiegte Verteidiger ihres Heimatlandes in einem ungleichen Kampf gegen die \u00fcberlegenen Kr\u00e4fte des Feindes auf. Sie waren nur f\u00fcnfhundert gegen fast f\u00fcnf- oder sechstausend der bolschewistischen Armee. Sie hielten den Feind nicht nur zur\u00fcck, sondern besiegten ihn auch. Ungleiche Kr\u00e4fte, ein zerm\u00fcrbender sechsst\u00fcndiger Kampf, in dem sich die Studenten der bolschewistischen Offensive entgegenstellten. Diese tapferen Menschen waren weder Kavalleristen noch professionell bewaffnet, aber das hielt sie nicht davon ab, die professionellen und gut bewaffneten Rotgardisten einen Viertel Tag lang aufzuhalten. Die Geschichte wiederholt sich immer wieder &#8230; Erst Kruty und jetzt in unserer Zeit der Flughafen Donezk. Die Krutyans sind der Prototyp der modernen Cyborgs. Sie sind unverw\u00fcstliche, engagierte Krieger, die bereit sind, ihr Volk und ihr Land zu verteidigen. Die Schlacht von Kruty wird oft mit der Schlacht der griechischen Krieger bei den Thermopylen verglichen. In der Tat gibt es eine \u00c4hnlichkeit &#8211; diese beiden Truppen gingen in den sicheren Tod gegen einen viel st\u00e4rkeren Gegner. Der spartanische K\u00f6nig zog freiwillig mit einem Trupp von 300 Spartanern los, um den Pass der Thermopylen zu verteidigen, w\u00e4hrend die \u00fcbrigen 6000 Griechen vor den barbarischen Heeren flohen. Bei dieser heldenhaften Verteidigung kamen der K\u00f6nig und seine gesamte Einheit ums Leben. Aber es gibt einen Unterschied zwischen diesen beiden Situationen. Die ukrainische Aktion unterscheidet sich dadurch, dass fast unausgebildete Studenten in die Schlacht zogen, w\u00e4hrend es bei den Thermopylen ausschlie\u00dflich die Garde des K\u00f6nigs war &#8211; abgeh\u00e4rtet in den schlimmsten K\u00e4mpfen, die besten der besten&#8221; K\u00e4mpfer Griechenlands. Im Falle der Ukraine gaben die Studenten alles f\u00fcr ihr Land.<\/p>\n<p>Mit Kruty begann eine neue Epoche in der Geschichte der Ukraine. Dieses Datum stellt den Beginn unserer Befreiungsrevolution dar, nicht die zahlreichen formalen Daten, die mit der Einberufung der Zentralen Rada, dann mit der Ver\u00f6ffentlichung dieses oder jenes Dokuments verbunden sind. Um etwas Neues und Modernes zu schaffen, darf man in der Regel nicht an den alten Ansichten festhalten, sondern muss etwas Neues schaffen, das trotzdem praktisch ist. Das haben uns die jungen Menschen gezeigt, die einen ungleichen Kampf gegen die Bolschewiki gef\u00fchrt haben. Ohne Kruty w\u00e4re auch ein solches Gesetz vom 22. Januar lediglich ein nicht unterzeichnetes Dokument gewesen. Denn es reicht nicht aus, solche Taten zu &#8220;verk\u00fcnden&#8221; &#8211; sie m\u00fcssen getan werden, denn &#8220;der hohe Rang unserer Ritter lehrt Treue zu den Idealen und die F\u00e4higkeit zu gehorchen. Nur Treue und Gehorsam schaffen die Voraussetzungen f\u00fcr den Erfolg des nationalen Kampfes. &#8220;Sie scheuten sich nicht, die Welt zu konfrontieren und ihre Ideen zu verteidigen, und so setzten sie ihre blutige Unterschrift unter eine formelle Verpflichtung vom 22. Januar.<\/p>\n<p>Ein Jahrhundert ist vergangen \u2013 der Feind hat flei\u00dfig alle Spuren vernichtet, aber es ist unbestreitbar wahr, dass die heutige Jugend der Ukraine mit ganzem Herzen, mit ihrem ganzen Wesen den Rang ihrer Vorg\u00e4nger f\u00fchlt. Sie wurden genau dort, in der N\u00e4he von Kruty, get\u00f6tet \u2013 erst erschossen und dann mit Bajonetten und Messern erledigt. Die Bauern, die der Hinrichtung beiwohnten, bezeugten, dass ein Sch\u00fcler der 7. Klasse die Hymne &#8220;Schtsche ne wmerla Ukrajina&#8221; sang, die von den anderen Sch\u00fclern aufgegriffen wurde.<\/p>\n<p>Wir m\u00fcssen uns an die Leistung von Kadetten und Schulkindern im Jahr 1918 erinnern, die uns in einer f\u00fcr unseren Staat so schwierigen Zeit ein Beispiel sein sollte. Sie haben uns gezeigt, dass wir unsere Ideen bis zum Ende verteidigen m\u00fcssen. Angesichts des Todes z\u00f6gerten die Jungen nicht &#8211; ein Beispiel f\u00fcr die aufopfernde Liebe zu ihrem Land. Krutys Helden k\u00e4mpften nicht f\u00fcr Geld, nicht f\u00fcr Ruhm, sondern f\u00fcr Frieden und Freiheit, Unabh\u00e4ngigkeit des Staates. Ihre letzten Worte waren die Zeilen der Hymne der Ukraine: \u201e\u2026Leib und Seele geben wir f\u00fcr unsere Freiheit\u2026\u201c .<\/p>","protected":false},"featured_media":682,"template":"","ua_history_cat":[5],"_links":{"self":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/ua-history\/159"}],"collection":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/ua-history"}],"about":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/types\/ua-history"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/media\/682"}],"wp:attachment":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/media?parent=159"}],"wp:term":[{"taxonomy":"ua_history_cat","embeddable":true,"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/ua_history_cat?post=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}