{"id":720,"date":"2021-04-23T03:33:58","date_gmt":"2021-04-23T00:33:58","guid":{"rendered":"http:\/\/ukraine-forum.eu\/?post_type=our_projects&#038;p=720"},"modified":"2021-08-13T14:13:26","modified_gmt":"2021-08-13T11:13:26","slug":"prosymo-daty-vidpovidi-na-nashi-lysty-vid-12-travnya-2020-roku-pro-sproby-znyshhennya-demokratiyi-ta-7-lypnya-2020-r-pro-ukrayinsku-movu","status":"publish","type":"our_projects","link":"https:\/\/ukraine-forum.eu\/de\/our_projects\/prosymo-daty-vidpovidi-na-nashi-lysty-vid-12-travnya-2020-roku-pro-sproby-znyshhennya-demokratiyi-ta-7-lypnya-2020-r-pro-ukrayinsku-movu\/","title":{"rendered":"Bitte antworten Sie auf unsere Briefe vom 12. Mai 2020 \u00fcber Versuche, die Demokratie zu zerst\u00f6ren und vom 7. Juli 2020 \u00fcber die ukrainische Sprache."},"content":{"rendered":"<p>Ruhm f\u00fcr die Ukraine, Herr Pr\u00e4sident!<\/p>\n<p>Am 12. Mai 2020 haben wir Ihnen unsere Briefe zu den Versuchen, die Demokratie in der Ukraine zu zerst\u00f6ren und die Patrioten und Freiwilligen des Maidan sowie den f\u00fcnften Pr\u00e4sidenten der Ukraine, Petro Poroschenko, absichtlich zu diskreditieren, geschickt. Bis heute haben wir Briefe von verschiedenen staatlichen Strukturen erhalten, die keine Antwort auf unseren Aufruf geben, der von 54 Ukrainern aus 11 L\u00e4ndern unterst\u00fctzt wurde. Wir bitten Sie, unseren Einspruch sorgf\u00e4ltig zu pr\u00fcfen und uns eine Antwort zur Begr\u00fcndetheit unseres Einspruchs zu geben.<\/p>\n<p>Dar\u00fcber hinaus haben wir Ihnen unseren Appell bez\u00fcglich der von dem Abgeordneten Ihrer Partei, Buzhanskyj, angedrohten Vernichtung der Sprachengesetzgebung durch die anti-ukrainischen Kr\u00e4fte \u00fcbermittelt. Wir bitten Sie zu erkl\u00e4ren, warum es in der Partei Sluha Narodu solche anti-ukrainischen Abgeordneten gibt.<\/p>\n<p>Wir schlagen vor, dass dem Abgeordneten Buzhanskyj das Recht entzogen wird, jemals f\u00fcr das Parlament zu kandidieren oder ein \u00f6ffentliches Amt zu bekleiden.<\/p>\n<p>Daher warten wir auf eine Antwort auf diese beiden Beschwerden.<\/p>\n<p>Kopien der Briefe werden hinzugef\u00fcgt.<\/p>","protected":false},"featured_media":113,"template":"","_links":{"self":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/our_projects\/720"}],"collection":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/our_projects"}],"about":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/types\/our_projects"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/media\/113"}],"wp:attachment":[{"href":"https:\/\/ukraine-forum.eu\/de\/wp-json\/wp\/v2\/media?parent=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}